{"id":6053,"date":"2021-09-16T22:31:27","date_gmt":"2021-09-16T20:31:27","guid":{"rendered":"https:\/\/stefline.com\/?post_type=members&#038;p=6053"},"modified":"2021-09-16T23:13:20","modified_gmt":"2021-09-16T21:13:20","slug":"michel-berger","status":"publish","type":"members","link":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/","title":{"rendered":"Michel Berger"},"content":{"rendered":"","protected":false},"featured_media":6064,"menu_order":0,"template":"","class_list":["post-6053","members","type-members","status-publish","has-post-thumbnail","hentry","membertype-dj"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/stefline.com\/index.php\/members\/michel-berger\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"STEFLINE RADIO - La 1\u00e8re Webradio Associative du vignoble nantais\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Michel Berger - STEFLINE RADIO\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/stefline.com\/index.php\/members\/michel-berger\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/stefline.com\/wp-content\/uploads\/2021\/09\/bienvenuenew2.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/stefline.com\/wp-content\/uploads\/2021\/09\/bienvenuenew2.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-09-16T20:31:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-09-16T21:13:20+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/steflineradio\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@stefline\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Michel Berger - STEFLINE RADIO\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/stefline.com\/wp-content\/uploads\/2021\/09\/bienvenuenew2.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/michel-berger\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stefline.com#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/stefline.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/#listItem\",\"name\":\"Membres de l&#039;\\u00e9quipe\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/#listItem\",\"position\":2,\"name\":\"Membres de l&#039;\\u00e9quipe\",\"item\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/membertype\\\/dj\\\/#listItem\",\"name\":\"Dj\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stefline.com#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/membertype\\\/dj\\\/#listItem\",\"position\":3,\"name\":\"Dj\",\"item\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/membertype\\\/dj\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/michel-berger\\\/#listItem\",\"name\":\"Michel Berger\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/#listItem\",\"name\":\"Membres de l&#039;\\u00e9quipe\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/michel-berger\\\/#listItem\",\"position\":4,\"name\":\"Michel Berger\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/membertype\\\/dj\\\/#listItem\",\"name\":\"Dj\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stefline.com\\\/#organization\",\"name\":\"STEFLINE RADIO\",\"description\":\"La 1\\u00e8re Webradio Associative du vignoble nantais\",\"url\":\"https:\\\/\\\/stefline.com\\\/\",\"telephone\":\"+33244683636\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/stefline.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/bienvenuenew2.jpg\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/michel-berger\\\/#organizationLogo\",\"width\":300,\"height\":300,\"caption\":\"Logo Stefline Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/michel-berger\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/steflineradio\\\/\",\"https:\\\/\\\/twitter.com\\\/stefline\",\"https:\\\/\\\/www.instagram.com\\\/stefline44\",\"https:\\\/\\\/soundcloud.com\\\/stefline\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/michel-berger\\\/#webpage\",\"url\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/michel-berger\\\/\",\"name\":\"Michel Berger - STEFLINE RADIO\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stefline.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/michel-berger\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/stefline.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Michel-Berger.jpg\",\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/michel-berger\\\/#mainImage\",\"width\":557,\"height\":720,\"caption\":\"Michel Berger (Les Artistes Ont la Parole) - Stefline Radio\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stefline.com\\\/index.php\\\/members\\\/michel-berger\\\/#mainImage\"},\"datePublished\":\"2021-09-16T22:31:27+02:00\",\"dateModified\":\"2021-09-16T23:13:20+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stefline.com\\\/#website\",\"url\":\"https:\\\/\\\/stefline.com\\\/\",\"name\":\"STEFLINE RADIO\",\"description\":\"La 1\\u00e8re Webradio Associative du vignoble nantais\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/stefline.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Michel Berger - STEFLINE RADIO","description":"","canonical_url":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/stefline.com#listItem","position":1,"name":"Accueil","item":"https:\/\/stefline.com","nextItem":{"@type":"ListItem","@id":"https:\/\/stefline.com\/index.php\/members\/#listItem","name":"Membres de l&#039;\u00e9quipe"}},{"@type":"ListItem","@id":"https:\/\/stefline.com\/index.php\/members\/#listItem","position":2,"name":"Membres de l&#039;\u00e9quipe","item":"https:\/\/stefline.com\/index.php\/members\/","nextItem":{"@type":"ListItem","@id":"https:\/\/stefline.com\/index.php\/membertype\/dj\/#listItem","name":"Dj"},"previousItem":{"@type":"ListItem","@id":"https:\/\/stefline.com#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/stefline.com\/index.php\/membertype\/dj\/#listItem","position":3,"name":"Dj","item":"https:\/\/stefline.com\/index.php\/membertype\/dj\/","nextItem":{"@type":"ListItem","@id":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/#listItem","name":"Michel Berger"},"previousItem":{"@type":"ListItem","@id":"https:\/\/stefline.com\/index.php\/members\/#listItem","name":"Membres de l&#039;\u00e9quipe"}},{"@type":"ListItem","@id":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/#listItem","position":4,"name":"Michel Berger","previousItem":{"@type":"ListItem","@id":"https:\/\/stefline.com\/index.php\/membertype\/dj\/#listItem","name":"Dj"}}]},{"@type":"Organization","@id":"https:\/\/stefline.com\/#organization","name":"STEFLINE RADIO","description":"La 1\u00e8re Webradio Associative du vignoble nantais","url":"https:\/\/stefline.com\/","telephone":"+33244683636","logo":{"@type":"ImageObject","url":"https:\/\/stefline.com\/wp-content\/uploads\/2021\/09\/bienvenuenew2.jpg","@id":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/#organizationLogo","width":300,"height":300,"caption":"Logo Stefline Radio"},"image":{"@id":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/steflineradio\/","https:\/\/twitter.com\/stefline","https:\/\/www.instagram.com\/stefline44","https:\/\/soundcloud.com\/stefline"]},{"@type":"WebPage","@id":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/#webpage","url":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/","name":"Michel Berger - STEFLINE RADIO","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/stefline.com\/#website"},"breadcrumb":{"@id":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/stefline.com\/wp-content\/uploads\/2021\/09\/Michel-Berger.jpg","@id":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/#mainImage","width":557,"height":720,"caption":"Michel Berger (Les Artistes Ont la Parole) - Stefline Radio"},"primaryImageOfPage":{"@id":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/#mainImage"},"datePublished":"2021-09-16T22:31:27+02:00","dateModified":"2021-09-16T23:13:20+02:00"},{"@type":"WebSite","@id":"https:\/\/stefline.com\/#website","url":"https:\/\/stefline.com\/","name":"STEFLINE RADIO","description":"La 1\u00e8re Webradio Associative du vignoble nantais","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/stefline.com\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"STEFLINE RADIO - La 1\u00e8re Webradio Associative du vignoble nantais","og:type":"article","og:title":"Michel Berger - STEFLINE RADIO","og:url":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/","og:image":"https:\/\/stefline.com\/wp-content\/uploads\/2021\/09\/bienvenuenew2.jpg","og:image:secure_url":"https:\/\/stefline.com\/wp-content\/uploads\/2021\/09\/bienvenuenew2.jpg","og:image:width":300,"og:image:height":300,"article:published_time":"2021-09-16T20:31:27+00:00","article:modified_time":"2021-09-16T21:13:20+00:00","article:publisher":"https:\/\/www.facebook.com\/steflineradio\/","twitter:card":"summary","twitter:site":"@stefline","twitter:title":"Michel Berger - STEFLINE RADIO","twitter:image":"https:\/\/stefline.com\/wp-content\/uploads\/2021\/09\/bienvenuenew2.jpg"},"aioseo_meta_data":{"post_id":"6053","title":"#post_title #separator_sa #site_title","description":"#post_content","keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-16 20:31:27","updated":"2025-06-04 11:46:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/stefline.com\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/stefline.com\/index.php\/members\/\" title=\"Membres de l&apos;\u00e9quipe\">Membres de l'\u00e9quipe<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/stefline.com\/index.php\/membertype\/dj\/\" title=\"Dj\">Dj<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMichel Berger\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/stefline.com"},{"label":"Membres de l&#039;\u00e9quipe","link":"https:\/\/stefline.com\/index.php\/members\/"},{"label":"Dj","link":"https:\/\/stefline.com\/index.php\/membertype\/dj\/"},{"label":"Michel Berger","link":"https:\/\/stefline.com\/index.php\/members\/michel-berger\/"}],"_links":{"self":[{"href":"https:\/\/stefline.com\/index.php\/wp-json\/wp\/v2\/members\/6053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stefline.com\/index.php\/wp-json\/wp\/v2\/members"}],"about":[{"href":"https:\/\/stefline.com\/index.php\/wp-json\/wp\/v2\/types\/members"}],"version-history":[{"count":1,"href":"https:\/\/stefline.com\/index.php\/wp-json\/wp\/v2\/members\/6053\/revisions"}],"predecessor-version":[{"id":6054,"href":"https:\/\/stefline.com\/index.php\/wp-json\/wp\/v2\/members\/6053\/revisions\/6054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stefline.com\/index.php\/wp-json\/wp\/v2\/media\/6064"}],"wp:attachment":[{"href":"https:\/\/stefline.com\/index.php\/wp-json\/wp\/v2\/media?parent=6053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}